{"id":17058,"date":"2020-12-30T04:05:51","date_gmt":"2020-12-30T04:05:51","guid":{"rendered":"https:\/\/www.mes-allocs.fr\/guides\/?p=17058"},"modified":"2025-06-20T12:39:26","modified_gmt":"2025-06-20T10:39:26","slug":"demande-ass","status":"publish","type":"post","link":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/","title":{"rendered":"Comment remplir une demande d&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique ?"},"content":{"rendered":"<p><a href=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17062 size-full\" title=\"Comment remplir une demande d'allocation de solidarit\u00e9 sp\u00e9cifique ?\" src=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\" alt=\"Comment remplir une demande d'allocation de solidarit\u00e9 sp\u00e9cifique ?\" width=\"1280\" height=\"326\" srcset=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg 1280w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604-300x76.jpg 300w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604-1024x261.jpg 1024w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604-768x196.jpg 768w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604-600x153.jpg 600w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p><strong>L&rsquo;ASS (Allocation de solidarit\u00e9 sp\u00e9cifique) permet aux demandeurs d&#8217;emploi de continuer \u00e0 toucher une aide apr\u00e8s l&rsquo;<a href=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\">ARE<\/a>. Comment remplir une demande d&rsquo; <a href=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\">allocation de solidarit\u00e9 sp\u00e9cifique<\/a> ?<\/strong><\/p>\n<div class='cta-block'><div class='text'>Simulez vos aides en 2 min.<\/div><a href='https:\/\/www.mes-allocs.fr\/ab-app?origin=guides\/wp-json\/wp\/v2\/posts\/17058' class='app-button fit'>Simulation gratuite<\/a><\/div>\n<h1>L&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique<\/h1>\n<h2>Qu&rsquo;est-ce que l&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique (ASS) ?<\/h2>\n<p><a href=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\">L&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique<\/a> est accord\u00e9e aux b\u00e9n\u00e9ficiaires de l&rsquo; allocation d&rsquo;aide au retour \u00e0 l&#8217;emploi (ARE) et qui sont encore en recherche d&rsquo; emploi.<\/p>\n<p>Pour b\u00e9n\u00e9ficier de l&rsquo; Allocation de solidarit\u00e9 sp\u00e9cifique, vous devez respecter les conditions d&rsquo;obtention de celle-ci :<\/p>\n<ul>\n<li>\u00catre apte au travail ;<\/li>\n<li>\u00catre demandeur d&rsquo; emploi ou cr\u00e9er\/reprendre une entreprise ;<\/li>\n<li>Avoir \u00e9puis\u00e9 vos droits \u00e0 l&rsquo;ARE ou \u00e0 la R\u00e9mun\u00e9ration de Fin de Formation (RFF) ;<\/li>\n<li>Avoir travaill\u00e9 au moins 5 ans (\u00e0 temps plein ou \u00e0 temps partiel) au cours des 10 ans avant la fin de votre dernier contrat de travail. Si vous avez arr\u00eat\u00e9 votre activit\u00e9 professionnelle pour \u00e9lever un enfant, les 5 ans sont r\u00e9duits d&rsquo; 1 an par enfant dans la limite de 3 ans. Toutes les p\u00e9riodes d&rsquo;activit\u00e9 sont prises en compte (CDD, CDI, contrat d&rsquo;int\u00e9rim, alternance, service national, formation professionnelle,&#8230;)\u00a0 ;<\/li>\n<li>Ne pas d\u00e9passer l&rsquo;\u00e2ge l\u00e9gal de d\u00e9part \u00e0 la retraite ;<\/li>\n<li>Ne pas d\u00e9passer le plafond de ressources mensuelles.<\/li>\n<\/ul>\n<p>Certaines cat\u00e9gories de demandeurs d&#8217;emploi peuvent demander l&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique. Ces cat\u00e9gories sont : les artistes non salari\u00e9s, les marins p\u00eacheurs, ou encore les ouvriers dockers occasionnels. L&rsquo;ASS leur sera vers\u00e9e tous les 6 mois renouvelables.<\/p>\n<p>Un demandeur d&#8217;emploi de plus de <b>50 ans<\/b> peut choisir de toucher l&rsquo;ASS au lieu de l&rsquo;ARE. Il peut cumuler l&rsquo;ASS avec une pension de vieillesse ou une pension militaire jusqu&rsquo;\u00e0 l&rsquo;\u00e2ge de sa retraite.<\/p>\n<h2>Quel est le plafond de ressources mensuelles pour recevoir l&rsquo;ASS ?<\/h2>\n<p>Le montant pris en compte est la moyenne des ressources des 12 mois pr\u00e9c\u00e9dents la demande d&rsquo;ASS. Les types de ressources qui sont prises en compte pour le calcul du montant de l&rsquo;ASS sont :<\/p>\n<ul>\n<li>Les ressources mensuelles ;<\/li>\n<li>D&rsquo;autres ressources comme les revenus des valeurs et capitaux mobiliers, les revenus fonciers ;<\/li>\n<li>Le montant de la pension alimentaire si vous en \u00eates b\u00e9n\u00e9ficiaire.<\/li>\n<\/ul>\n<p>Pour recevoir l&rsquo;ASS, vos ressources mensuelles ne doivent pas d\u00e9passer :<\/p>\n<ul>\n<li><strong>1 353,10 \u20ac si vous \u00eates seul<\/strong> ;<\/li>\n<li><strong>2 126,30 <\/strong><span class=\"prix\"><strong>\u20ac si vous \u00eates en couple<\/strong> ( mariage, Pacs ou concubinage).<\/span><\/li>\n<\/ul>\n<h2>Quelles sont les d\u00e9marches pour recevoir l&rsquo;ASS ?<\/h2>\n<p data-wp-editing=\"1\">Une demande d\u2019allocation sp\u00e9cifique est envoy\u00e9e automatiquement 30 jours avant la fin de vos <a href=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\/droit-au-chomage\">droits \u00e0 l&rsquo; allocation ch\u00f4mage<\/a> si vous \u00eates indemnis\u00e9 par <a href=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-17063\" title=\"Quelles sont les d\u00e9marches pour recevoir l'ASS ?\" src=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599-1024x682.jpg\" alt=\"Quelles sont les d\u00e9marches pour recevoir l'ASS ?\" width=\"461\" height=\"307\" srcset=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599-1024x682.jpg 1024w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599-300x200.jpg 300w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599-768x512.jpg 768w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599-600x400.jpg 600w, https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-pixabay-261599.jpg 1280w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/a>P\u00f4le\u00a0emploi. Si aucune demande automatique n&rsquo;a \u00e9t\u00e9 faite, vous pouvez faire une demande dans une agence P\u00f4le emploi. Il faut alors d\u00e9poser la demande compl\u00e9t\u00e9e et sign\u00e9e avec les justificatifs d\u2019activit\u00e9 avant la fin des droits \u00e0 l&rsquo;ARE pour \u00e9viter une rupture d\u2019indemnisation.<\/p>\n<p>Pour votre premi\u00e8re demande d&rsquo;ASS, le montant de l&rsquo;ASS est calcul\u00e9 en tenant compte de vos ressources suivantes :<\/p>\n<ul>\n<li>vos revenus per\u00e7us au cours des 12 derniers mois avant le dernier jour de votre ARE ;<\/li>\n<li>vos revenus d\u00e9clar\u00e9s aux imp\u00f4ts ;<\/li>\n<li>les revenus de la personne avec qui vous \u00eates en couple (conjoint(e), mariage, Pacs).<\/li>\n<\/ul>\n<p>En temps normal, un formulaire vous est adress\u00e9 par P\u00f4le emploi \u00e0 la fin de vos droits pour l&rsquo;Allocation d&rsquo;aide au Retour \u00e0 l&rsquo; Emploi (ARE).<\/p>\n<p><strong>L&rsquo; ASS est vers\u00e9e sur une p\u00e9riode de 6 mois renouvelable<\/strong>. Lorsque vous \u00eates en fin de p\u00e9riode d&rsquo;indemnisation, P\u00f4le emploi vous envoie une demande de renouvellement automatiquement. Vous devrez la remplir et la corriger.<\/p>\n<h2>Comment remplir une demande d&rsquo;allocation de solidarit\u00e9 sp\u00e9cifique ?<\/h2>\n<p>Les\u00a0<strong>documents \u00e0 fournir \u00e0 la demande d\u2019allocation de solidarit\u00e9 sp\u00e9cifique<\/strong>\u00a0sont\u00a0:<\/p>\n<ul>\n<li>Des copies des certificats de travail correspondant aux dix derni\u00e8res ann\u00e9es<\/li>\n<li>Les justificatifs des situations assimil\u00e9es \u00e0 des p\u00e9riodes de travail<\/li>\n<li>Une copie du dernier avis d\u2019imposition et le cas \u00e9ch\u00e9ant celui du conjoint<\/li>\n<\/ul>\n<p>Dans certaines situations, vous devrez fournir avec votre demande l\u2019allocation, les justificatifs et documents suivants :<\/p>\n<ul>\n<li>La d\u00e9cision d\u2019attribution du revenu minimum d\u2019insertion ou revenu de solidarit\u00e9 active<\/li>\n<li>La d\u00e9cision d\u2019attribution de l\u2019allocation parentale d\u2019\u00e9ducation.<\/li>\n<\/ul>\n<h2>Quand s&rsquo;arr\u00eate le versement de l&rsquo;ASS?<\/h2>\n<p>Si vous \u00eates sans emploi, le paiement de l&rsquo;ASS cesse si vous vous trouvez dans l&rsquo;un des cas suivants :<\/p>\n<ul>\n<li>Ressources sup\u00e9rieures aux plafonds.<\/li>\n<li>Absence de recherche d&#8217;emploi.<\/li>\n<li>Suivi d&rsquo;une formation r\u00e9mun\u00e9r\u00e9e.<\/li>\n<li>Reprise d&rsquo;une activit\u00e9 non cumulable avec l&rsquo;ASS.<\/li>\n<li>Perception d&rsquo;indemnit\u00e9s journali\u00e8res pour maladie, maternit\u00e9 ou accident du travail.<\/li>\n<li>Suppression des allocations par d\u00e9cision du pr\u00e9fet ou suite \u00e0 une radiation.<\/li>\n<li>Perception de l&rsquo;allocation de pr\u00e9sence parentale ou l&rsquo;allocation journali\u00e8re d&rsquo;une personne en fin de vie.<\/li>\n<li>Possibilit\u00e9 de b\u00e9n\u00e9ficier d&rsquo;une retraite \u00e0 taux plein ou atteinte de l&rsquo;\u00e2ge limite d&rsquo;activit\u00e9.<\/li>\n<\/ul>\n<p>Si vous travaillez, le paiement de l&rsquo;ASS s&rsquo;arr\u00eate apr\u00e8s 3 mois (cons\u00e9cutifs ou non) de cumul avec les r\u00e9mun\u00e9rations de votre activit\u00e9 professionnelle :<\/p>\n<ul>\n<li>Si votre activit\u00e9 professionnelle se poursuit, le versement de l&rsquo;ASS est interrompu. \u00c0 la fin du 6<sup>e<\/sup> mois suivant la reprise d&rsquo;activit\u00e9, vous pourrez percevoir la prime d&rsquo;activit\u00e9 en compl\u00e9ment de votre r\u00e9mun\u00e9ration, si vous remplissez les conditions.<\/li>\n<li>Si votre activit\u00e9 professionnelle s&rsquo;interrompt et que s&rsquo;en suit une p\u00e9riode d&rsquo;inactivit\u00e9 d&rsquo;au moins 3 mois cons\u00e9cutifs, une nouvelle p\u00e9riode de cumul est possible.<\/li>\n<\/ul>\n<h2>Quelle est votre protection sociale lorsque vous touchez l&rsquo;ASS ?<\/h2>\n<p>Si vous \u00eates malade, la s\u00e9curit\u00e9 sociale ou la MSA continuera \u00e0 vous rembourser , les frais m\u00e9dicaux, de pharmacie, d\u2019hospitalisation. La s\u00e9curit\u00e9 sociale calculera vos droits aux indemnit\u00e9s journali\u00e8res en cas d\u2019arr\u00eat maladie \u00e0 partir de vos anciens salaires.<\/p>\n<p>Si vous \u00eates enceinte, la s\u00e9curit\u00e9 sociale ou MSA calculera vos droits au cong\u00e9 maternit\u00e9.<\/p>\n<p>Si vous \u00eates proche de la retraite, les p\u00e9riodes de ch\u00f4mage indemnis\u00e9es en ASS comptent dans le calcul du nombre de trimestres valid\u00e9s pour la retraite.<\/p>\n<p><iframe loading=\"lazy\" title=\"L&#039;ASS\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/QAulvUZqyHk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h1>Quel est le montant de l&rsquo;ASS ?<\/h1>\n<p>Le montant des indemnit\u00e9s journali\u00e8res de l&rsquo;ASS est de <b>19,33 <\/b><strong><span class=\"prix\">\u20ac<\/span><\/strong> (579,90 <span class=\"prix\">\u20ac<\/span> pour 1 mois de 30 jours).<\/p>\n<h2>Vous \u00eates sans emploi<\/h2>\n<p><strong>Si vous \u00eates sans emploi et que vous \u00eates seul, le montant de l&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique se calcule ainsi :<\/strong><\/p>\n\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-290\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"2\"\n           data-rows=\"4\"\n           data-wpID=\"290\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell wpdt-bold wpdt-fs-000016 wpdt-bc-FFFFFF\"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:50%;                    padding:10px;\n                    \"\n                    >\n                                        Ressources mensuelles                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-bold wpdt-fs-000016 wpdt-bc-FFFFFF\"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:50%;                    padding:10px;\n                    \"\n                    >\n                                        Montant mensuel de l'ASS                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Moins de 773,20 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        579,90 \u20ac                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        De 773,20 \u20ac \u00e0 1 353,10 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        1 353,10 \u20ac (avant d\u00e9duction du montant de vos ressources)                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Sup\u00e9rieures \u00e0 1 353,10 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Non \u00e9ligible au versement de l'ASS                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-290'>\n.wpdt-fs-000016 { font-size: 16px !important;}\n.wpdt-bc-FFFFFF { background-color: #FFFFFF !important;}\n<\/style>\n\n<p><strong>Si vous \u00eates sans emploi et que vous \u00eates en couple, le montant de votre ASS se calcule ainsi :<\/strong><\/p>\n\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-291\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"2\"\n           data-rows=\"4\"\n           data-wpID=\"291\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell wpdt-bold wpdt-fs-000016 wpdt-bc-FFFFFF\"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:50%;                    padding:10px;\n                    \"\n                    >\n                                        Ressources mensuelles                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-bold wpdt-fs-000016 wpdt-bc-FFFFFF\"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:50%;                    padding:10px;\n                    \"\n                    >\n                                        Montant mensuel de l'ASS                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Moins de 1 546,40 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        579,90 \u20ac                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        De 1 546,40 \u20ac \u00e0 2 126,30 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        2 126,30 \u20ac (avant d\u00e9duction du montant de vos ressources)                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Sup\u00e9rieures \u00e0 2 126,30 \u20ac                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Non \u00e9ligible au versement de l'ASS                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-291'>\n.wpdt-fs-000016 { font-size: 16px !important;}\n.wpdt-bc-FFFFFF { background-color: #FFFFFF !important;}\n<\/style>\n\n<div class='cta-block'><div class='text'>Simulez toutes vos aides en 2 min.<\/div><a href='https:\/\/www.mes-allocs.fr\/ab-app?origin=guides\/wp-json\/wp\/v2\/posts\/17058' class='app-button fit'>Simulation gratuite<\/a><\/div>\n<h2>Vous travaillez<\/h2>\n<p>Depuis le 1er septembre 2017, avec le d\u00e9cret n 2017-826, il existe de nouvelles r\u00e8gles de cumul de l\u2019allocation de solidarit\u00e9 sp\u00e9cifique (ASS) avec les r\u00e9mun\u00e9rations de reprise d&rsquo; activit\u00e9.<\/p>\n<p><strong>Selon le code du travail, les personnes b\u00e9n\u00e9ficiant de l\u2019ASS qui reprennent une activit\u00e9 professionnelle (salari\u00e9e ou non salari\u00e9e)\u00a0 peuvent cumuler leur r\u00e9mun\u00e9ration avec leur allocation pendant trois mois<\/strong>. Ce dispositif d &lsquo;int\u00e9ressement concerne toutes les personnes qui b\u00e9n\u00e9ficient de l&rsquo;ASS.<\/p>\n<p>Apr\u00e8s les trois mois de cumul, le versement de l\u2019ASS est arr\u00eat\u00e9 si l\u2019int\u00e9ress\u00e9 poursuit son activit\u00e9. Les demandeurs d\u2019emploi qui ne peuvent plus b\u00e9n\u00e9ficier de l&rsquo;ASS auront un acc\u00e8s facilit\u00e9 \u00e0 la prime d\u2019activit\u00e9, s&rsquo;ils remplissent les conditions d\u2019attribution.<\/p>\n<p>Attention : depuis le 1er septembre 2017, la prime forfaitaire d&rsquo;activit\u00e9 est supprim\u00e9e. Elle \u00e9tait vers\u00e9e par P\u00f4le emploi et \u00e9tait donn\u00e9e aux b\u00e9n\u00e9ficiaires de l&rsquo;ASS qui reprenaient un emploi. Son montant \u00e9tait de 150 euros par mois. \u00a0Sous certaines conditions, les demandeurs d&#8217;emploi b\u00e9n\u00e9ficiaires de l&rsquo;ASS\u00a0 avant le 1<sup>er<\/sup> septembre 2017 qui ont repris une activit\u00e9 professionnelle, avant cette m\u00eame date peuvent obtenir cette prime.<\/p>\n<div class='cta-block'><div class='text'>Simulez toutes vos aides en 2 min.<\/div><a href='https:\/\/www.mes-allocs.fr\/ab-app?origin=guides\/wp-json\/wp\/v2\/posts\/17058' class='app-button fit'>Simulation gratuite<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ASS (Allocation de solidarit\u00e9 sp\u00e9cifique) permet aux demandeurs d&#8217;emploi de continuer \u00e0 toucher une aide apr\u00e8s l&rsquo;ARE. Comment remplir une demande d&rsquo; allocation de solidarit\u00e9 sp\u00e9cifique ? L&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique Qu&rsquo;est-ce que l&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique (ASS) ? L&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique est accord\u00e9e aux b\u00e9n\u00e9ficiaires de l&rsquo; allocation d&rsquo;aide au retour \u00e0 l&#8217;emploi [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":17062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3736,2989],"tags":[],"class_list":["post-17058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allocation-de-solidarite-specifique","category-chomage"],"acf":{"faq":{"1":{"question":"Qui a droit \u00e0 l'allocation de solidarit\u00e9 sp\u00e9cifique ?","answer":"Le droit \u00e0 l'allocation de solidarit\u00e9 sp\u00e9cifique est accord\u00e9 aux personnes dont les droits \u00e0 l'ARE arrivent \u00e0 leur fin.\r\n<br> <a href=\"https:\/\/www.mes-allocs.fr\/guides\/pole-emploi\/allocation-de-solidarite-specifique\/comment-remplir-demande-allocation-solidarite-specifique\/\">Lire la suite<\/a>\r\n\r\n\r\n"},"2":{"question":"Qu'est-ce que l'allocation de solidarit\u00e9 sp\u00e9cifique ?","answer":"L'ASS est une allocation qui vient remplacer l'ARE lorsque le b\u00e9n\u00e9ficiaire des allocations ch\u00f4mage ne peut plus avoir droit \u00e0 celles-ci.\r\n"},"3":{"question":"Quel est le montant de l'ASS ?","answer":"Depuis 2025, le montant journalier de l'ASS est de 19,33 euros.\r\n<br> <a href=\"https:\/\/www.mes-allocs.fr\/guides\/pole-emploi\/allocation-de-solidarite-specifique\/comment-remplir-demande-allocation-solidarite-specifique\/\">Lire la suite<\/a>\r\n\r\n"},"4":{"question":"Quelles aides sociales peut-on cumuler avec l'ASS ?","answer":"Vous pouvez cumuler l'ASS avec le RSA et la pension d'invalidit\u00e9 sous certaines conditions."},"5":{"question":"Est-ce que les ann\u00e9es de ch\u00f4mage comptent pour la retraite ?","answer":"Les ann\u00e9es de ch\u00f4mage indemnis\u00e9 sont consid\u00e9r\u00e9es comme des trimestres d'assurance retraite au r\u00e9gime g\u00e9n\u00e9ral de la S\u00e9curit\u00e9 sociale dans la limite de 4 trimestres par an. \r\n<br> <a href=\"https:\/\/www.mes-allocs.fr\/guides\/pole-emploi\/allocation-de-solidarite-specifique\/comment-remplir-demande-allocation-solidarite-specifique\/\">Lire la suite<\/a>\r\n\r\n"},"6":{"question":"Quelle allocation apr\u00e8s fin de droit ch\u00f4mage ?","answer":"Si vous avez \u00e9puis\u00e9 vos droits \u00e0 l'ARE, vous pouvez toucher l'ASS."},"7":{"question":"","answer":""},"8":{"question":"","answer":""},"9":{"question":"","answer":""},"10":{"question":"","answer":""},"11":{"question":"","answer":""},"12":{"question":"","answer":""},"13":{"question":"","answer":""},"14":{"question":"","answer":""},"15":{"question":"","answer":""},"16":{"question":"","answer":""}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment remplir une demande d&#039;Allocation de solidarit\u00e9 sp\u00e9cifique ?<\/title>\n<meta name=\"description\" content=\"L&#039;ASS vient en aide aux demandeurs d&#039;emploi. Comment remplir une demande d&#039; allocation de solidarit\u00e9 sp\u00e9cifique ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment remplir une demande d&#039;Allocation de solidarit\u00e9 sp\u00e9cifique ?\" \/>\n<meta property=\"og:description\" content=\"L&#039;ASS vient en aide aux demandeurs d&#039;emploi. Comment remplir une demande d&#039; allocation de solidarit\u00e9 sp\u00e9cifique ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes-Allocs.fr\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T04:05:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T10:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"326\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabiola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabiola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/\"},\"author\":{\"name\":\"Fabiola\",\"@id\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/#\\\/schema\\\/person\\\/1c4837d5703727cb02ce84583b5a44aa\"},\"headline\":\"Comment remplir une demande d&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique ?\",\"datePublished\":\"2020-12-30T04:05:51+00:00\",\"dateModified\":\"2025-06-20T10:39:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/\"},\"wordCount\":1399,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\",\"articleSection\":[\"Allocation de solidarit\u00e9 sp\u00e9cifique\",\"France Travail &amp; Ch\u00f4mage\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/\",\"url\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/\",\"name\":\"Comment remplir une demande d'Allocation de solidarit\u00e9 sp\u00e9cifique ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\",\"datePublished\":\"2020-12-30T04:05:51+00:00\",\"dateModified\":\"2025-06-20T10:39:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/#\\\/schema\\\/person\\\/1c4837d5703727cb02ce84583b5a44aa\"},\"description\":\"L'ASS vient en aide aux demandeurs d'emploi. Comment remplir une demande d' allocation de solidarit\u00e9 sp\u00e9cifique ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg\",\"width\":1280,\"height\":326,\"caption\":\"pexels sora shimazaki 5673491 1 e1608587562604\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/chomage\\\/allocation-de-solidarite-specifique\\\/demande-ass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment remplir une demande d&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/#website\",\"url\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/\",\"name\":\"Mes-Allocs.fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/test.mes-allocs.fr\\\/guides\\\/#\\\/schema\\\/person\\\/1c4837d5703727cb02ce84583b5a44aa\",\"name\":\"Fabiola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fabiola-150x150.png\",\"url\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fabiola-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fabiola-150x150.png\",\"caption\":\"Fabiola\"},\"description\":\"Fabiola est r\u00e9dactrice au sein de l'\u00e9quipe Mes Allocs, sp\u00e9cialis\u00e9e en sciences politiques et affaires publiques. Dipl\u00f4m\u00e9e de l'HEIP, elle rejoint Mes Allocs apr\u00e8s une premi\u00e8re exp\u00e9rience \u00e0 l'Assembl\u00e9e Nationale.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cecilia-philippe-b-8a8085195\"],\"url\":\"https:\\\/\\\/www.mes-allocs.fr\\\/guides\\\/auteurs\\\/fabiola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment remplir une demande d'Allocation de solidarit\u00e9 sp\u00e9cifique ?","description":"L'ASS vient en aide aux demandeurs d'emploi. Comment remplir une demande d' allocation de solidarit\u00e9 sp\u00e9cifique ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment remplir une demande d'Allocation de solidarit\u00e9 sp\u00e9cifique ?","og_description":"L'ASS vient en aide aux demandeurs d'emploi. Comment remplir une demande d' allocation de solidarit\u00e9 sp\u00e9cifique ?","og_url":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/","og_site_name":"Mes-Allocs.fr","article_published_time":"2020-12-30T04:05:51+00:00","article_modified_time":"2025-06-20T10:39:26+00:00","og_image":[{"width":1280,"height":326,"url":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg","type":"image\/jpeg"}],"author":"Fabiola","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Fabiola","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#article","isPartOf":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/"},"author":{"name":"Fabiola","@id":"https:\/\/test.mes-allocs.fr\/guides\/#\/schema\/person\/1c4837d5703727cb02ce84583b5a44aa"},"headline":"Comment remplir une demande d&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique ?","datePublished":"2020-12-30T04:05:51+00:00","dateModified":"2025-06-20T10:39:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/"},"wordCount":1399,"commentCount":4,"image":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg","articleSection":["Allocation de solidarit\u00e9 sp\u00e9cifique","France Travail &amp; Ch\u00f4mage"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/","url":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/","name":"Comment remplir une demande d'Allocation de solidarit\u00e9 sp\u00e9cifique ?","isPartOf":{"@id":"https:\/\/test.mes-allocs.fr\/guides\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#primaryimage"},"image":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg","datePublished":"2020-12-30T04:05:51+00:00","dateModified":"2025-06-20T10:39:26+00:00","author":{"@id":"https:\/\/test.mes-allocs.fr\/guides\/#\/schema\/person\/1c4837d5703727cb02ce84583b5a44aa"},"description":"L'ASS vient en aide aux demandeurs d'emploi. Comment remplir une demande d' allocation de solidarit\u00e9 sp\u00e9cifique ?","breadcrumb":{"@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#primaryimage","url":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg","contentUrl":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2020\/12\/pexels-sora-shimazaki-5673491-1-e1608587562604.jpg","width":1280,"height":326,"caption":"pexels sora shimazaki 5673491 1 e1608587562604"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mes-allocs.fr\/guides\/chomage\/allocation-de-solidarite-specifique\/demande-ass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.mes-allocs.fr\/guides\/"},{"@type":"ListItem","position":2,"name":"Comment remplir une demande d&rsquo;Allocation de solidarit\u00e9 sp\u00e9cifique ?"}]},{"@type":"WebSite","@id":"https:\/\/test.mes-allocs.fr\/guides\/#website","url":"https:\/\/test.mes-allocs.fr\/guides\/","name":"Mes-Allocs.fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.mes-allocs.fr\/guides\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/test.mes-allocs.fr\/guides\/#\/schema\/person\/1c4837d5703727cb02ce84583b5a44aa","name":"Fabiola","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2021\/06\/fabiola-150x150.png","url":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2021\/06\/fabiola-150x150.png","contentUrl":"https:\/\/www.mes-allocs.fr\/guides\/wp-content\/uploads\/2021\/06\/fabiola-150x150.png","caption":"Fabiola"},"description":"Fabiola est r\u00e9dactrice au sein de l'\u00e9quipe Mes Allocs, sp\u00e9cialis\u00e9e en sciences politiques et affaires publiques. Dipl\u00f4m\u00e9e de l'HEIP, elle rejoint Mes Allocs apr\u00e8s une premi\u00e8re exp\u00e9rience \u00e0 l'Assembl\u00e9e Nationale.","sameAs":["https:\/\/www.linkedin.com\/in\/cecilia-philippe-b-8a8085195"],"url":"https:\/\/www.mes-allocs.fr\/guides\/auteurs\/fabiola\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/posts\/17058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/comments?post=17058"}],"version-history":[{"count":19,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/posts\/17058\/revisions"}],"predecessor-version":[{"id":100909,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/posts\/17058\/revisions\/100909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/media\/17062"}],"wp:attachment":[{"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/media?parent=17058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/categories?post=17058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mes-allocs.fr\/guides\/wp-json\/wp\/v2\/tags?post=17058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}